{"id":20451,"date":"2026-07-02T10:20:36","date_gmt":"2026-07-02T11:20:36","guid":{"rendered":"https:\/\/ticketzentrum.buehnen-graz.com\/vorstellung\/2026-10-21-193000-4\/"},"modified":"2026-07-02T10:20:36","modified_gmt":"2026-07-02T11:20:36","slug":"2026-10-21-193000-4","status":"publish","type":"th-event","link":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/vorstellung\/2026-10-21-193000-4\/","title":{"rendered":"2026-10-21 19:30:00"},"template":"","productions":[3060],"event-category":[657],"event-place":[1278],"season":[1611],"class_list":["post-20451","th-event","type-th-event","status-publish","hentry","th-production-anja-om-plus-folk-art-festival-2026","th-category-konzerte","th-place-heimatsaal-graz-im-volkskundemuseum","th-season-2026-27"],"nelio_popups_active_popup":"","acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>2026-10-21 19:30:00 | Ticketzentrum<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"2026-10-21 19:30:00 | Ticketzentrum\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ticketzentrum.buehnen-graz.com\/vorstellung\/2026-10-21-193000-4\/\" \/>\n<meta property=\"og:site_name\" content=\"Ticketzentrum\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/vorstellung\\\/2026-10-21-193000-4\\\/\",\"url\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/vorstellung\\\/2026-10-21-193000-4\\\/\",\"name\":\"2026-10-21 19:30:00 | Ticketzentrum\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/#website\"},\"datePublished\":\"2026-07-02T11:20:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/vorstellung\\\/2026-10-21-193000-4\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/vorstellung\\\/2026-10-21-193000-4\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/vorstellung\\\/2026-10-21-193000-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vorstellungen\",\"item\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/vorstellungen\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"2026-10-21 19:30:00\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/#website\",\"url\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/\",\"name\":\"Ticketzentrum der B\u00fchnen Graz\",\"description\":\"Ticketzentrum bietet online Tickets zu verschiedenen Kultur- und Entertainmentevents rund um Graz\",\"publisher\":{\"@id\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/#organization\",\"name\":\"art + event | Theaterservice Graz GmbH\",\"url\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/app\\\/uploads\\\/2024\\\/05\\\/tz-logo-header.png\",\"contentUrl\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/app\\\/uploads\\\/2024\\\/05\\\/tz-logo-header.png\",\"width\":278,\"height\":36,\"caption\":\"art + event | Theaterservice Graz GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/ticketzentrum.buehnen-graz.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"2026-10-21 19:30:00 | Ticketzentrum","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"2026-10-21 19:30:00 | Ticketzentrum","og_url":"https:\/\/ticketzentrum.buehnen-graz.com\/vorstellung\/2026-10-21-193000-4\/","og_site_name":"Ticketzentrum","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ticketzentrum.buehnen-graz.com\/vorstellung\/2026-10-21-193000-4\/","url":"https:\/\/ticketzentrum.buehnen-graz.com\/vorstellung\/2026-10-21-193000-4\/","name":"2026-10-21 19:30:00 | Ticketzentrum","isPartOf":{"@id":"https:\/\/ticketzentrum.buehnen-graz.com\/#website"},"datePublished":"2026-07-02T11:20:36+00:00","breadcrumb":{"@id":"https:\/\/ticketzentrum.buehnen-graz.com\/vorstellung\/2026-10-21-193000-4\/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ticketzentrum.buehnen-graz.com\/vorstellung\/2026-10-21-193000-4\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ticketzentrum.buehnen-graz.com\/vorstellung\/2026-10-21-193000-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/"},{"@type":"ListItem","position":2,"name":"Vorstellungen","item":"https:\/\/ticketzentrum.buehnen-graz.com\/vorstellungen\/"},{"@type":"ListItem","position":3,"name":"2026-10-21 19:30:00"}]},{"@type":"WebSite","@id":"https:\/\/ticketzentrum.buehnen-graz.com\/#website","url":"https:\/\/ticketzentrum.buehnen-graz.com\/","name":"Ticketzentrum der B\u00fchnen Graz","description":"Ticketzentrum bietet online Tickets zu verschiedenen Kultur- und Entertainmentevents rund um Graz","publisher":{"@id":"https:\/\/ticketzentrum.buehnen-graz.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ticketzentrum.buehnen-graz.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/ticketzentrum.buehnen-graz.com\/#organization","name":"art + event | Theaterservice Graz GmbH","url":"https:\/\/ticketzentrum.buehnen-graz.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/ticketzentrum.buehnen-graz.com\/#\/schema\/logo\/image\/","url":"https:\/\/ticketzentrum.buehnen-graz.com\/app\/uploads\/2024\/05\/tz-logo-header.png","contentUrl":"https:\/\/ticketzentrum.buehnen-graz.com\/app\/uploads\/2024\/05\/tz-logo-header.png","width":278,"height":36,"caption":"art + event | Theaterservice Graz GmbH"},"image":{"@id":"https:\/\/ticketzentrum.buehnen-graz.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/events\/20451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/events"}],"about":[{"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/types\/th-event"}],"version-history":[{"count":1,"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/events\/20451\/revisions"}],"predecessor-version":[{"id":20453,"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/events\/20451\/revisions\/20453"}],"wp:attachment":[{"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/media?parent=20451"}],"wp:term":[{"taxonomy":"th-production","embeddable":true,"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/productions?post=20451"},{"taxonomy":"th-category","embeddable":true,"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/event-category?post=20451"},{"taxonomy":"th-place","embeddable":true,"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/event-place?post=20451"},{"taxonomy":"th-season","embeddable":true,"href":"https:\/\/ticketzentrum.buehnen-graz.com\/en\/wp-json\/wp\/v2\/season?post=20451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}